{"id":470,"date":"2026-03-09T15:42:07","date_gmt":"2026-03-09T20:42:07","guid":{"rendered":"https:\/\/intactica.com.co\/?page_id=470"},"modified":"2026-03-13T03:35:33","modified_gmt":"2026-03-13T08:35:33","slug":"blog","status":"publish","type":"page","link":"http:\/\/intactica.com.co\/index.php\/blog\/","title":{"rendered":"Blog"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"470\" class=\"elementor elementor-470\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ae58b3 e-flex e-con-boxed e-con e-parent\" data-id=\"5ae58b3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-53ca20f elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-card-shadow-yes elementor-posts__hover-gradient elementor-widget elementor-widget-posts\" data-id=\"53ca20f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;pagination_type&quot;:&quot;numbers&quot;,&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-658 post type-post status-publish format-standard has-post-thumbnail hentry category-tendencias post-with-thumbnail post-with-thumbnail-large\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"http:\/\/intactica.com.co\/index.php\/2026\/03\/13\/descubrir-tendencias-para-conectar-con-los-consumidores\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1714\" height=\"1235\" src=\"http:\/\/intactica.com.co\/wp-content\/uploads\/2026\/03\/Imag-Tend-3.png\" class=\"attachment-full size-full wp-image-686\" alt=\"\" srcset=\"http:\/\/intactica.com.co\/wp-content\/uploads\/2026\/03\/Imag-Tend-3.png 1714w, http:\/\/intactica.com.co\/wp-content\/uploads\/2026\/03\/Imag-Tend-3-300x216.png 300w, http:\/\/intactica.com.co\/wp-content\/uploads\/2026\/03\/Imag-Tend-3-1024x738.png 1024w, http:\/\/intactica.com.co\/wp-content\/uploads\/2026\/03\/Imag-Tend-3-768x553.png 768w, http:\/\/intactica.com.co\/wp-content\/uploads\/2026\/03\/Imag-Tend-3-1536x1107.png 1536w\" sizes=\"(max-width: 1714px) 100vw, 1714px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Tendencias<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"http:\/\/intactica.com.co\/index.php\/2026\/03\/13\/descubrir-tendencias-para-conectar-con-los-consumidores\/\" >\n\t\t\t\tDescubrir tendencias para conectar con los consumidores\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Descubrir tendencias para conectar con los consumidores Antes de abordar el concepto de tendencia, es importante comprender qu\u00e9 es y qu\u00e9 no es. Una tendencia no es lo mismo que una moda. Aunque puede influir<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"http:\/\/intactica.com.co\/index.php\/2026\/03\/13\/descubrir-tendencias-para-conectar-con-los-consumidores\/\" aria-label=\"Read more about Descubrir tendencias para conectar con los consumidores\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t13 de marzo de 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-470","page","type-page","status-publish","hentry","post","post-with-thumbnail","post-with-thumbnail-large"],"_links":{"self":[{"href":"http:\/\/intactica.com.co\/index.php\/wp-json\/wp\/v2\/pages\/470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/intactica.com.co\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/intactica.com.co\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/intactica.com.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/intactica.com.co\/index.php\/wp-json\/wp\/v2\/comments?post=470"}],"version-history":[{"count":13,"href":"http:\/\/intactica.com.co\/index.php\/wp-json\/wp\/v2\/pages\/470\/revisions"}],"predecessor-version":[{"id":708,"href":"http:\/\/intactica.com.co\/index.php\/wp-json\/wp\/v2\/pages\/470\/revisions\/708"}],"wp:attachment":[{"href":"http:\/\/intactica.com.co\/index.php\/wp-json\/wp\/v2\/media?parent=470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}